{"id":7458,"count":2,"description":"","link":"\/blog\/tag\/best-international-series\/","name":"best international series","slug":"best-international-series","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/tags\/7458"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"\/blog\/wp-json\/wp\/v2\/posts?tags=7458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}